{"id":7398,"date":"2024-08-02T14:16:19","date_gmt":"2024-08-02T14:16:19","guid":{"rendered":"https:\/\/trustpair.com\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/"},"modified":"2024-08-26T13:08:11","modified_gmt":"2024-08-26T13:08:11","slug":"evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place","status":"publish","type":"post","link":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/","title":{"rendered":"\u00c9valuation des tiers en entreprise : 14 actions \u00e0 mettre en place"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Dans le cadre du livre blanc \u00ab\u00a0<strong>Gestion des tiers et conformit\u00e9 : le guide pratique<\/strong>\u00ab\u00a0, Trustpair donne la parole \u00e0 Benjamin Van Gaver, Partner au cabinet d&rsquo;avocat August Debouzy. Dans l&rsquo;objectif d&rsquo;expliquer ce qu&rsquo;est la loi Sapin II et de donner les clefs aux services financiers pour d\u00e9ployer et appliquer cette r\u00e9glementation en toute conformit\u00e9, cet expert partage les grandes \u00e9tapes \u00e0 respecter afin de proc\u00e9der \u00e0 une bonne \u00e9valuation des tiers en entreprise. Afin de d\u00e9finir un tel dispositif, les Directions financi\u00e8res peuvent se baser sur le <\/span><a href=\"https:\/\/www.agence-francaise-anticorruption.gouv.fr\/files\/files\/2019-01-29_-_Guide_pratique_fonction_conformite.pdf\"><span style=\"font-weight: 400;\">guide technique de l\u2019AFA<\/span><\/a> &#8211; Agence Fran\u00e7aise Anticorruption gouvernementale &#8211; qui <span style=\"font-weight: 400;\">propose 14 crit\u00e8res \u00e0 suivre pour assurer l&rsquo;\u00e9valuation des tiers. Les entreprises peuvent ainsi consid\u00e9rer par elles-m\u00eames si un tiers est \u00e0 risque ou pas. <strong>Cet article partage la <\/strong><\/span><strong>liste principale des \u00e9l\u00e9ments \u00e0 v\u00e9rifier pour assurer la conformit\u00e9 de votre activit\u00e9.\u00a0<\/strong><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-d211a27c-f915-42c9-9726-c0c86b6d8f0f\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-d211a27c-f915-42c9-9726-c0c86b6d8f0f\" class=\"hs-cta-node hs-cta-d211a27c-f915-42c9-9726-c0c86b6d8f0f\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/5278241\/d211a27c-f915-42c9-9726-c0c86b6d8f0f\" target=\"_blank\" rel=\"noopener noreferrer\"><img fetchpriority=\"high\" decoding=\"async\" id=\"hs-cta-img-d211a27c-f915-42c9-9726-c0c86b6d8f0f\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/5278241\/d211a27c-f915-42c9-9726-c0c86b6d8f0f.png\" alt=\"T\u00e9l\u00e9chargement Livre blanc Conformit\u00e9 et gestion des tiers Trustpair\" width=\"1200\" height=\"630\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(5278241, 'd211a27c-f915-42c9-9726-c0c86b6d8f0f', {}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><strong>1. L\u2019identit\u00e9 du tiers<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Il s\u2019agit pour l\u2019entreprise de recenser les principaux \u00e9l\u00e9ments d\u2019identit\u00e9 du tiers, ce que l\u2019on pourrait d\u00e9finir comme son \u00e9tat-civil. Selon que le tiers est une personne physique ou une personne morale, les points \u00e0 traiter varient : nom, pr\u00e9nom, raison sociale, nature juridique de la structure, objet social, date de cr\u00e9ation, date de naissance, capital, effectifs, chiffre d&rsquo;affaires, secteur(s) d\u2019activit\u00e9, comp\u00e9tences, implantation(s) g\u00e9ographique(s), etc&#8230;<\/span><\/p>\n<h2><strong>2. Les actionnaires principaux et b\u00e9n\u00e9ficiaires effectifs<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">L\u2019entreprise doit identifier les nom, pr\u00e9nom et date de naissance des actionnaires principaux du tiers, ainsi que ses b\u00e9n\u00e9ficiaires effectifs. Ce dernier terme d\u00e9signe toute personne physique ou morale qui poss\u00e8de directement ou indirectement plus de 25 % du capital ou des droits de vote.\u00a0<\/span><\/p>\n<h2><strong>3. Le risque pays sur le plan corruption si le tiers travaille avec l\u2019\u00e9tranger ou y est implant\u00e9<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Une proc\u00e9dure d\u2019\u00e9valuation de la sensibilit\u00e9 des pays au regard du risque de corruption est indispensable. Outre les indications apport\u00e9es par la cartographie des risques et l\u2019exp\u00e9rience de l\u2019organisation sur le pays concern\u00e9, voici une s\u00e9lection de sources objectives permettant de compl\u00e9ter l\u2019\u00e9valuation du risque pays de fa\u00e7on fiable :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">listes officielles des pays sous sanctions financi\u00e8res et internationales publi\u00e9es par les minist\u00e8res ;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">rapports de suivi de l\u2019OCDE au sujet de la mise en \u0153uvre de la convention sur la corruption d\u2019agents publics \u00e9trangers dans les transactions commerciales (<\/span><a href=\"http:\/\/www.oecd.org\/fr\/corruption\/conventionsurlaluttecontrelacorruptiondagentspublicsetrangersdanslestransactionscommercialesinternationales.htm\"><span style=\"font-weight: 400;\">pays signataires<\/span><\/a><span style=\"font-weight: 400;\">) ;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">l\u2019indice <\/span><a href=\"https:\/\/transparency-france.org\/actu\/indice-de-perception-de-la-corruption-2018\/\"><span style=\"font-weight: 400;\">CPI<\/span><\/a><span style=\"font-weight: 400;\"> de perception de la corruption publi\u00e9 par l\u2019organisation non-gouvernementale Transparency International.<\/span><\/li>\n<\/ul>\n<h2><strong>4. Le risque sectoriel selon la sensibilit\u00e9 \u00e0 la corruption du secteur d\u2019activit\u00e9 du tiers<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Le niveau du risque de corruption chez un tiers peut varier selon le secteur d\u2019activit\u00e9, plus ou moins sensible pour des raisons historiques ou culturelles par exemple. Cette liste sectorielle doit \u00eatre mise \u00e0 jour r\u00e9guli\u00e8rement selon les informations issues de la cartographie des risques et de l\u2019exp\u00e9rience de l\u2019entreprise.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">On peut compl\u00e9ter avec la liste indicative publi\u00e9e par l\u2019organisation non-gouvernementale Transparency International (<\/span><a href=\"https:\/\/www.transparency.org\/whatwedo\/publication\/bpi_2011\"><span style=\"font-weight: 400;\">Transparency International Bribes Payer Index Report 2011<\/span><\/a><span style=\"font-weight: 400;\">). G\u00e9n\u00e9ralement, on d\u00e9termine le risque sectoriel selon le niveau de sensibilit\u00e9 des secteurs d\u2019activit\u00e9 dans lesquels le tiers r\u00e9alise ses diff\u00e9rents revenus.<\/span><\/p>\n<h2><strong>5. L\u2019expertise du tiers au regard de la mission qui va lui \u00eatre confi\u00e9e<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">L\u2019entreprise s\u2019assure que la tierce partie \u00e9valu\u00e9e dispose de l\u2019exp\u00e9rience, des qualifications et des comp\u00e9tences n\u00e9cessaires \u00e0 la r\u00e9alisation de sa mission. La r\u00e9mun\u00e9ration doit \u00eatre coh\u00e9rente au regard de l\u2019expertise et du travail effectu\u00e9.\u00a0<\/span><\/p>\n<h2><strong>6. La r\u00e9putation d\u2019int\u00e9grit\u00e9 du tiers avec lequel elle va engager une relation\u00a0<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">L\u2019entreprise v\u00e9rifie, dans les m\u00e9dias ou sur Internet par exemple, si le tiers, ses dirigeants, ses principaux actionnaires et ses b\u00e9n\u00e9ficiaires effectifs sont ou ont \u00e9t\u00e9 l\u2019objet d\u2019informations d\u00e9favorables : all\u00e9gations, pol\u00e9miques, poursuites ou condamnations pour des faits d\u00e9lictueux en g\u00e9n\u00e9ral, et en particulier sur le sujet de la corruption.<\/span><\/p>\n<h2><strong>7. La mise en place par le tiers d\u2019un process de conformit\u00e9 en interne<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">L\u2019entreprise doit rechercher si le tiers a effectu\u00e9 les d\u00e9marches n\u00e9cessaires pour \u00e9tablir un dispositif interne de conformit\u00e9 anticorruption.\u00a0<\/span><\/p>\n<h2><strong>8. Le niveau de coop\u00e9ration du tiers dans la proc\u00e9dure d\u2019\u00e9valuation en cours<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Le comportement du tiers doit \u00eatre int\u00e9gr\u00e9 \u00e0 l\u2019\u00e9valuation : si un tiers refuse de fournir les informations ou documents demand\u00e9s, ou s\u2019il tarde \u00e0 le faire, cela peut \u00eatre d\u00e9fini comme aggravant lors de l\u2019\u00e9valuation du niveau de risque.<\/span><\/p>\n<h2><strong>9. La nature et l\u2019objet de la relation avec le tiers<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">L\u2019entreprise se doit de ma\u00eetriser avec pr\u00e9cision les conditions d\u2019ex\u00e9cution du contrat, le niveau de risque du tiers demeurant \u00e0 ajuster selon le contenu exact de la relation contractuelle.<\/span><\/p>\n<h2><strong>10. L\u2019\u00e9valuation par les tiers de leurs propres tiers<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Dans un \u00e9cosyst\u00e8me avec de multiples intervenants, l\u2019entreprise n\u2019est pas n\u00e9cessairement li\u00e9e formellement avec chacun d\u2019entre eux. Il est alors conseill\u00e9 de veiller \u00e0 ce que les tiers avec lesquels l\u2019entreprise est li\u00e9e prennent en charge s\u00e9rieusement l\u2019\u00e9valuation de leurs propres tiers.<\/span><\/p>\n<h2><strong>11. L\u2019interaction du tiers avec des agents publics ou des personnes politiquement expos\u00e9es (PPE)<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Les relations public\/priv\u00e9 repr\u00e9sentent un risque identifi\u00e9 en terme de corruption. Il faut identifier les interactions que le tiers peut avoir avec des agents publics, en recueillant a minima nom, pr\u00e9nom et date de naissance. Cela se justifie \u00e0 fortiori lorsqu\u2019il s\u2019agit de <\/span><span style=\"font-weight: 400;\">personnes politiquement expos\u00e9es<\/span><span style=\"font-weight: 400;\">, c\u2019est-\u00e0-dire les personnes physiques qui exercent ou ont exerc\u00e9 d\u2019importantes fonctions publiques au sein de leur pays, d\u2019un pays \u00e9tranger ou d\u2019une organisation internationale, et qui peuvent parfois disposer d\u2019un r\u00e9el pouvoir de d\u00e9cision au sein de tiers.<\/span><\/p>\n<h2><strong>12. Les aspects financiers en jeu : dur\u00e9e, montants impliqu\u00e9s et devises utilis\u00e9es<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">L\u2019\u00e9tablissement d\u2019une relation financi\u00e8re sur la longue dur\u00e9e et\/ou des montants \u00e9lev\u00e9s peuvent s\u2019av\u00e9rer un facteur aggravant au moment de l\u2019\u00e9valuation des tiers et de leur niveau de risque.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La devise concern\u00e9e doit aussi \u00eatre prise en consid\u00e9ration, et cela relativement au fait de l\u2019extraterritorialit\u00e9 de certaines lois anticorruption \u00e9trang\u00e8res.<\/span><\/p>\n<h2><strong>13. Les modalit\u00e9s de la r\u00e9mun\u00e9ration du tiers<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Le montant factur\u00e9 et \u00e0 payer doit \u00eatre coh\u00e9rent avec la nature et l\u2019ampleur des biens ou services vendus par le tiers, et conforme au prix du march\u00e9, qu\u2019il s\u2019agisse d\u2019un fournisseur, prestataire ou interm\u00e9diaire. Si une incoh\u00e9rence \u00e9tait identifi\u00e9e sur ce plan, l\u2019\u00e9valuation des tiers s\u2019interromprait le temps d\u2019en justifier les raisons.<\/span><\/p>\n<h2><strong>14. La conformit\u00e9 des modalit\u00e9s et flux de paiements par rapport aux pratiques habituelles<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">La localisation du compte bancaire du tiers peut constituer un facteur aggravant lors de l\u2019\u00e9valuation du niveau de risque du tiers (par exemple, un compte bancaire domicili\u00e9 dans un Etat non-coop\u00e9ratif).<\/span><\/p>\n<p>Pour vous accompagner l&rsquo;\u00e9valuation des tiers et vous permettre de mettre en place un dispositif pertinent, Trustpair vous propose de d\u00e9couvrir ces sujets dans son <a href=\"https:\/\/info.trustpair.fr\/livre-blanc-evaluation-tiers-conformite\" target=\"_blank\" rel=\"noopener noreferrer\">livre blanc d\u00e9di\u00e9<\/a>.<\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-1f932da1-79b8-4e3f-9c34-223a0c23c1ad\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-1f932da1-79b8-4e3f-9c34-223a0c23c1ad\" class=\"hs-cta-node hs-cta-1f932da1-79b8-4e3f-9c34-223a0c23c1ad\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/5278241\/1f932da1-79b8-4e3f-9c34-223a0c23c1ad\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" id=\"hs-cta-img-1f932da1-79b8-4e3f-9c34-223a0c23c1ad\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/5278241\/1f932da1-79b8-4e3f-9c34-223a0c23c1ad.png\" alt=\"GIF T\u00e9l\u00e9chargement Libre Blanc Gestion des tiers et conformit\u00e9 Trustpair\" width=\"1179\" height=\"619\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(5278241, '1f932da1-79b8-4e3f-9c34-223a0c23c1ad', {}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du livre blanc \u00ab\u00a0Gestion des tiers et conformit\u00e9 : le guide pratique\u00ab\u00a0, Trustpair donne la parole \u00e0 Benjamin Van Gaver, Partner au cabinet d&rsquo;avocat August Debouzy. Dans l&rsquo;objectif d&rsquo;expliquer ce qu&rsquo;est la loi Sapin II et de donner les clefs aux services financiers pour d\u00e9ployer et appliquer cette r\u00e9glementation en toute conformit\u00e9, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81],"tags":[],"class_list":["post-7398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conformite_finance"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;\u00e9valuation des tiers en entreprise en 14 \u00e9tapes - Trustpair<\/title>\n<meta name=\"description\" content=\"Pour proc\u00e9der \u00e0 l&#039;\u00e9valuation des tiers en toute conformit\u00e9, Benjamin Van Gaver, Partner au cabinet d&#039;avocat August Debouzy d\u00e9crypte le guide de l&#039;AFA\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;\u00e9valuation des tiers en entreprise en 14 \u00e9tapes - Trustpair\" \/>\n<meta property=\"og:description\" content=\"Pour proc\u00e9der \u00e0 l&#039;\u00e9valuation des tiers en toute conformit\u00e9, Benjamin Van Gaver, Partner au cabinet d&#039;avocat August Debouzy d\u00e9crypte le guide de l&#039;AFA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/\" \/>\n<meta property=\"og:site_name\" content=\"Trustpair\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T14:16:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T13:08:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trustpair.com\/wp-content\/uploads\/dispositif.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"trustpair_2438\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"trustpair_2438\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/\"},\"author\":{\"name\":\"trustpair_2438\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/person\\\/84e7e0fdbda12c03dbbe6629de190034\"},\"headline\":\"\u00c9valuation des tiers en entreprise : 14 actions \u00e0 mettre en place\",\"datePublished\":\"2024-08-02T14:16:19+00:00\",\"dateModified\":\"2024-08-26T13:08:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/\"},\"wordCount\":1230,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/dispositif.png\",\"articleSection\":[\"Conformit\u00e9 finance\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/\",\"url\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/\",\"name\":\"L'\u00e9valuation des tiers en entreprise en 14 \u00e9tapes - Trustpair\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/dispositif.png\",\"datePublished\":\"2024-08-02T14:16:19+00:00\",\"dateModified\":\"2024-08-26T13:08:11+00:00\",\"description\":\"Pour proc\u00e9der \u00e0 l'\u00e9valuation des tiers en toute conformit\u00e9, Benjamin Van Gaver, Partner au cabinet d'avocat August Debouzy d\u00e9crypte le guide de l'AFA\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/dispositif.png\",\"contentUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/dispositif.png\",\"width\":1000,\"height\":524},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9valuation des tiers en entreprise : 14 actions \u00e0 mettre en place\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/\",\"name\":\"Trustpair\",\"description\":\"Solution leader de pr\u00e9vention de la fraude au virement et de contr\u00f4le RIB fournisseurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#organization\",\"name\":\"Trustpair\",\"url\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-trustpair.svg\",\"contentUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-trustpair.svg\",\"width\":304,\"height\":73,\"caption\":\"Trustpair\"},\"image\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/person\\\/84e7e0fdbda12c03dbbe6629de190034\",\"name\":\"trustpair_2438\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g\",\"caption\":\"trustpair_2438\"},\"sameAs\":[\"http:\\\/\\\/trustpair.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'\u00e9valuation des tiers en entreprise en 14 \u00e9tapes - Trustpair","description":"Pour proc\u00e9der \u00e0 l'\u00e9valuation des tiers en toute conformit\u00e9, Benjamin Van Gaver, Partner au cabinet d'avocat August Debouzy d\u00e9crypte le guide de l'AFA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/","og_locale":"fr_FR","og_type":"article","og_title":"L'\u00e9valuation des tiers en entreprise en 14 \u00e9tapes - Trustpair","og_description":"Pour proc\u00e9der \u00e0 l'\u00e9valuation des tiers en toute conformit\u00e9, Benjamin Van Gaver, Partner au cabinet d'avocat August Debouzy d\u00e9crypte le guide de l'AFA","og_url":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/","og_site_name":"Trustpair","article_published_time":"2024-08-02T14:16:19+00:00","article_modified_time":"2024-08-26T13:08:11+00:00","og_image":[{"width":1000,"height":524,"url":"https:\/\/trustpair.com\/wp-content\/uploads\/dispositif.png","type":"image\/png"}],"author":"trustpair_2438","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"trustpair_2438","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/#article","isPartOf":{"@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/"},"author":{"name":"trustpair_2438","@id":"https:\/\/trustpair.com\/fr\/#\/schema\/person\/84e7e0fdbda12c03dbbe6629de190034"},"headline":"\u00c9valuation des tiers en entreprise : 14 actions \u00e0 mettre en place","datePublished":"2024-08-02T14:16:19+00:00","dateModified":"2024-08-26T13:08:11+00:00","mainEntityOfPage":{"@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/"},"wordCount":1230,"commentCount":0,"publisher":{"@id":"https:\/\/trustpair.com\/fr\/#organization"},"image":{"@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/#primaryimage"},"thumbnailUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/dispositif.png","articleSection":["Conformit\u00e9 finance"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/","url":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/","name":"L'\u00e9valuation des tiers en entreprise en 14 \u00e9tapes - Trustpair","isPartOf":{"@id":"https:\/\/trustpair.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/#primaryimage"},"image":{"@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/#primaryimage"},"thumbnailUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/dispositif.png","datePublished":"2024-08-02T14:16:19+00:00","dateModified":"2024-08-26T13:08:11+00:00","description":"Pour proc\u00e9der \u00e0 l'\u00e9valuation des tiers en toute conformit\u00e9, Benjamin Van Gaver, Partner au cabinet d'avocat August Debouzy d\u00e9crypte le guide de l'AFA","breadcrumb":{"@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/#primaryimage","url":"https:\/\/trustpair.com\/wp-content\/uploads\/dispositif.png","contentUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/dispositif.png","width":1000,"height":524},{"@type":"BreadcrumbList","@id":"https:\/\/trustpair.com\/fr\/blog\/evaluation-des-tiers-en-entreprise-14-actions-a-mettre-en-place\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trustpair.com\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9valuation des tiers en entreprise : 14 actions \u00e0 mettre en place"}]},{"@type":"WebSite","@id":"https:\/\/trustpair.com\/fr\/#website","url":"https:\/\/trustpair.com\/fr\/","name":"Trustpair","description":"Solution leader de pr\u00e9vention de la fraude au virement et de contr\u00f4le RIB fournisseurs","publisher":{"@id":"https:\/\/trustpair.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trustpair.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trustpair.com\/fr\/#organization","name":"Trustpair","url":"https:\/\/trustpair.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trustpair.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/trustpair.com\/wp-content\/uploads\/2024\/07\/Logo-trustpair.svg","contentUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/2024\/07\/Logo-trustpair.svg","width":304,"height":73,"caption":"Trustpair"},"image":{"@id":"https:\/\/trustpair.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/trustpair.com\/fr\/#\/schema\/person\/84e7e0fdbda12c03dbbe6629de190034","name":"trustpair_2438","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g","caption":"trustpair_2438"},"sameAs":["http:\/\/trustpair.com"]}]}},"_links":{"self":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/posts\/7398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/comments?post=7398"}],"version-history":[{"count":0,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/posts\/7398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/media\/7399"}],"wp:attachment":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/media?parent=7398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/categories?post=7398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/tags?post=7398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}