{"id":7325,"date":"2024-08-02T14:15:49","date_gmt":"2024-08-02T14:15:49","guid":{"rendered":"https:\/\/trustpair.com\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/"},"modified":"2024-08-26T13:08:07","modified_gmt":"2024-08-26T13:08:07","slug":"swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises","status":"publish","type":"post","link":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/","title":{"rendered":"Swiftref x Trustpair : la donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises"},"content":{"rendered":"<p><b><span style=\"font-weight: 400;\">Fond\u00e9e en 2017, <a href=\"https:\/\/trustpair.fr\/\">Trustpair<\/a> est une plateforme SaaS (Software as a Service) qui <\/span><\/b><span style=\"font-weight: 400;\">automatise la <\/span><span style=\"font-weight: 400;\">d\u00e9tection des erreurs et fraudes aux virements bancaires<\/span><b><span style=\"font-weight: 400;\"> en entreprises en v\u00e9rifiant les coordonn\u00e9es bancaires et les donn\u00e9es juridico-l\u00e9gales de leurs fournisseurs.<\/span><\/b><\/p>\n<h2><b>Enjeu<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">L\u2019Intelligence Artificielle utilis\u00e9e par Trustpair s\u2019appuie sur la m\u00e9thode du <strong>Machine Learning<\/strong> . La solution s\u2019adapte aux comportements et aux besoins de chaque entreprise cliente sans aucune configuration ou maintenance humaine.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour r\u00e9pondre aux besoins des entreprises, la plateforme Trustpair offre <strong>s\u00e9curit\u00e9<\/strong> et <strong>rapidit\u00e9 d\u2019installation<\/strong> sans perturber l\u2019environnement existant des clients.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Baptiste Collot, Alexandre Gillier et Simon Elcham se sont appuy\u00e9s sur leur exp\u00e9rience dans les domaines de la gestion de tr\u00e9sorerie et des services num\u00e9riques. Ils ont pour objectif de r\u00e9pondre \u00e0 la demande du march\u00e9 en mati\u00e8re \u00e0 : <\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">traiter les donn\u00e9es ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">r\u00e9duire les risques relatifs aux paiements.<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Ils ont identifi\u00e9 une probl\u00e9matique majeure dans le secteur. L<strong>a quantit\u00e9 des donn\u00e9es g\u00e9n\u00e9r\u00e9e est difficile \u00e0 contr\u00f4ler et \u00e0 analyser manuellement. <\/strong>Cela conduit \u00e0 des anomalies et des erreurs non d\u00e9tect\u00e9es dans les bases tiers.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour r\u00e9pondre \u00e0 cet enjeu, ils ont d\u00e9velopp\u00e9 une solution qui fonctionne en deux \u00e9tapes.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\"><strong>La base de donn\u00e9es des comptes fournisseurs d\u2019une entreprise est d\u2019abord analys\u00e9e.<\/strong> Elle est ensuite raffin\u00e9e pour \u00e9liminer les donn\u00e9es client inexactes ou obsol\u00e8tes. Celles-ci repr\u00e9sentent en moyenne 30% \u00e0 50% du total, une proportion qui peut avoir d\u2019importantes cons\u00e9quences sur l\u2019activit\u00e9.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"><strong>Le Machine Learning est ensuite d\u00e9ploy\u00e9. Il recherche les probl\u00e8mes et irr\u00e9gularit\u00e9s<\/strong><\/span><span style=\"font-weight: 400;\"> dans la cha\u00eene de paiement d\u2019une entreprise, comme les incoh\u00e9rences au niveau des dates et des montants. Trustpair exploite des donn\u00e9es issues de sources diverses : d\u00e9p\u00f4ts l\u00e9gaux, dossiers d\u00e9tenus par les clients et <a href=\"https:\/\/www.swift.com\/our-solutions\/compliance-and-shared-services\/swiftref\" target=\"_blank\" rel=\"noopener noreferrer\">sources priv\u00e9es<\/a> comme SWIFTRef.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Son service offre ainsi aux entreprises un moyen efficace et peu co\u00fbteux de<a href=\"https:\/\/trustpair.fr\/solutions\/protection-fraude-au-virement\/\"><strong> protection contre la fraude au viremen<\/strong><strong>t<\/strong><\/a>.<\/span><\/p>\n<p><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-cdcede09-afbd-460d-8a89-428c76842967\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-cdcede09-afbd-460d-8a89-428c76842967\" class=\"hs-cta-node hs-cta-cdcede09-afbd-460d-8a89-428c76842967\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><a href=\"https:\/\/cta-redirect.hubspot.com\/cta\/redirect\/5278241\/cdcede09-afbd-460d-8a89-428c76842967\" target=\"_blank\" rel=\"noopener noreferrer\"><img fetchpriority=\"high\" decoding=\"async\" id=\"hs-cta-img-cdcede09-afbd-460d-8a89-428c76842967\" class=\"hs-cta-img\" style=\"border-width: 0px;\" src=\"https:\/\/no-cache.hubspot.com\/cta\/default\/5278241\/cdcede09-afbd-460d-8a89-428c76842967.png\" alt=\"Nouveau call-to-action\" width=\"900\" height=\"305\" \/><\/a><\/span><script charset=\"utf-8\" src=\"https:\/\/js.hscta.net\/cta\/current.js\"><\/script><script type=\"text\/javascript\"> hbspt.cta.load(5278241, 'cdcede09-afbd-460d-8a89-428c76842967', {}); <\/script><\/span><!-- end HubSpot Call-to-Action Code --><\/p>\n<h2><b>Int\u00e9r\u00eat des donn\u00e9es de r\u00e9f\u00e9rence de SWIFTRef<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La valeur d\u2019une solution bas\u00e9e sur des donn\u00e9es repose sur celle des donn\u00e9es exploit\u00e9es. <\/span><span style=\"font-weight: 400;\">Qualit\u00e9 et fiabilit\u00e9 sont cruciales pour \u00e9viter que la solution n\u2019\u00e9choue au premier obstacle.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u00ab\u00a0<em>Trustpair nous permet de contr\u00f4ler \u00e9troitement les paiements et donn\u00e9es de nos fournisseurs. <\/em><\/span><span style=\"font-weight: 400;\"><em>Avec l\u2019\u00e9volution des techniques de fraude et les \u00e9normes quantit\u00e9s de donn\u00e9es \u00e0 traiter, les risques de fraude et d\u2019erreurs sont aujourd&rsquo;hui trop \u00e9lev\u00e9s pour se contenter de contr\u00f4les manuels. Cette solution digitale est un v\u00e9ritable atout pour l\u2019efficacit\u00e9 de nos proc\u00e9dures de contr\u00f4le.<\/em>\u00a0\u00bb Arnaud de Ligniville, Directeur Tr\u00e9sorerie, <a href=\"https:\/\/www.axereal.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ax\u00e9r\u00e9al<\/a><\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\"><em>\u00ab\u00a0En analysant plusieurs sources de donn\u00e9es, nous avons remarqu\u00e9 que nombre d\u2019entre elles reposent sur SWIFTRef\u00a0\u00bb<\/em>, explique Baptiste Collot, CEO de Trustpair. <em>\u00ab\u00a0Nous avons donc d\u00e9cid\u00e9 d\u2019aller directement \u00e0 la source tout en travaillant avec une organisation reconnue, ce qui est rassurant.\u00a0\u00bb<\/em> La solution de donn\u00e9es de r\u00e9f\u00e9rence de SWIFTRef pr\u00e9sente de nombreux avantages que Trustpair d\u00e9ploie avec succ\u00e8s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Trustpair utilise des API pour proposer des donn\u00e9es \u00ab sur demande \u00bb. En effet, elle fournit des fichiers volumineux trait\u00e9s individuellement par des syst\u00e8mes de back-office.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La solution Trustpair permet aussi d\u2019acc\u00e9der \u00e0 ces paquets de donn\u00e9es le plus efficacement possible. Elle fournit des donn\u00e9es de r\u00e9f\u00e9rence de paiement exactes, internationales et actualis\u00e9es sur des institutions financi\u00e8res dans plus de 200 pays.<\/span><\/p>\n<h3><strong>L\u2019optimisation des traitements en fait la solution la plus efficace du march\u00e9 tout en minimisant les \u00e9checs et retards<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Trustpair peut enfin v\u00e9ritablement compter sur notre s\u00e9curit\u00e9 in\u00e9gal\u00e9e et notre service disponible 24h\/24, 7j\/7.<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">\u00ab\u00a0<em>En tant qu\u2019ancien tr\u00e9sorier, je connaissais la valeur et la r\u00e9putation de SWIFT. La qualit\u00e9 de nos \u00e9changes avec les \u00e9quipes et la cr\u00e9ation d\u2019une offre sur-mesure nous permettant de satisfaire aux exigences tr\u00e8s \u00e9lev\u00e9es que nous nous fixons au quotidien chez Trustpair, afin de proposer \u00e0 nos clients la solution la plus avanc\u00e9e du march\u00e9.<\/em>\u00a0\u00bb Baptiste Collot, CEO de Trustpair<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Outre la fiabilit\u00e9 de SWIFTRef, notre position sur le march\u00e9 nous permet d\u2019offrir \u00e0 Trustpair le plus large \u00e9ventail de donn\u00e9es possible. Notamment les IBAN et BIC utilis\u00e9s par ses services reposant sur l\u2019apprentissage automatique. Gr\u00e2ce \u00e0 la <strong>vaste biblioth\u00e8que de donn\u00e9es de SWIFTRef<\/strong>, toutes les donn\u00e9es partielles re\u00e7ues par notre client peuvent \u00eatre compl\u00e9t\u00e9es par r\u00e9f\u00e9rencement crois\u00e9 avec les donn\u00e9es que nous fournissons pour am\u00e9liorer le profil du fournisseur. <strong>SWIFTRef b\u00e9n\u00e9ficiant de la certification ISO<\/strong>, Trustpair dispose de donn\u00e9es dans des formats standardis\u00e9s. Ainsi, au-del\u00e0 des gains d\u2019efficacit\u00e9 que l\u2019automatisation permet, elles assurent une <strong>rapidit\u00e9 d\u2019analyse et de <a href=\"https:\/\/trustpair.fr\/solutions\/nettoyage-base-tiers\/\">nettoyage des bases fournisseurs<\/a><\/strong>, et donc une poursuite de sa croissance.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Avec SWIFTRef, Trustpair a \u00e9galement acc\u00e8s \u00e0 l\u2019ensemble de la galaxie <a href=\"https:\/\/www.swift.com\/swift_in_french\" target=\"_blank\" rel=\"noopener noreferrer\">SWIFT<\/a> : LEI, identifiants bancaires nationaux, outils de v\u00e9rification d\u2019IBAN, instructions de r\u00e8glement standard (SSI), etc.<\/span><\/p>\n<hr \/>\n<h2><strong>\u00c0 propos de Swiftref<\/strong><\/h2>\n<p>Nous fournissons \u00e0 notre communaut\u00e9 une plateforme pour la messagerie, des standards pour communiquer et nous proposons des produits et des services pour faciliter l&rsquo;acc\u00e8s et l&rsquo;int\u00e9gration ; l&rsquo;identification, l&rsquo;analyse et la conformit\u00e9 en mati\u00e8re de lutte contre la criminalit\u00e9 financi\u00e8re.<\/p>\n<p>Notre plateforme de messagerie, nos produits et nos services connectent plus de 11 000 organisations bancaires et de titres, infrastructures de march\u00e9 et entreprises clientes dans plus de 200 pays et territoires, leur permettant de communiquer en toute s\u00e9curit\u00e9 et d&rsquo;\u00e9changer des messages financiers d&rsquo;une mani\u00e8re fiable.<\/p>\n<p>Nous visons constamment l&rsquo;excellence op\u00e9rationnelle et nous recherchons en permanence des moyens de r\u00e9duire les co\u00fbts, d&rsquo;att\u00e9nuer les risques et d&rsquo;\u00e9liminer les inefficacit\u00e9s op\u00e9rationnelles.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<h4><!--HubSpot Call-to-Action Code --><span id=\"hs-cta-wrapper-0cfd9cbd-df56-41a3-afce-b3d8bea86184\" class=\"hs-cta-wrapper\"><span id=\"hs-cta-0cfd9cbd-df56-41a3-afce-b3d8bea86184\" class=\"hs-cta-node hs-cta-0cfd9cbd-df56-41a3-afce-b3d8bea86184\"><!-- [if lte IE 8]>\n\n\n<div id=\"hs-cta-ie-element\"><\/div>\n\n\n<![endif]--><\/span><\/span><!-- end HubSpot Call-to-Action Code --><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Fond\u00e9e en 2017, Trustpair est une plateforme SaaS (Software as a Service) qui automatise la d\u00e9tection des erreurs et fraudes aux virements bancaires en entreprises en v\u00e9rifiant les coordonn\u00e9es bancaires et les donn\u00e9es juridico-l\u00e9gales de leurs fournisseurs. Enjeu L\u2019Intelligence Artificielle utilis\u00e9e par Trustpair s\u2019appuie sur la m\u00e9thode du Machine Learning . La solution s\u2019adapte aux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7326,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89,80],"tags":[],"class_list":["post-7325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-finance","category-actualites-trustpair"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises - Trustpair<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment Trustpair, en partenariat avec SwiftRef, collecte de la donn\u00e9e bancaire de r\u00e9f\u00e9rence pour \u00e9valuer les tiers. Lire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises - Trustpair\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment Trustpair, en partenariat avec SwiftRef, collecte de la donn\u00e9e bancaire de r\u00e9f\u00e9rence pour \u00e9valuer les tiers. Lire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/\" \/>\n<meta property=\"og:site_name\" content=\"Trustpair\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T14:15:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-26T13:08:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trustpair.com\/wp-content\/uploads\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"trustpair_2438\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"trustpair_2438\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/\"},\"author\":{\"name\":\"trustpair_2438\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/person\\\/84e7e0fdbda12c03dbbe6629de190034\"},\"headline\":\"Swiftref x Trustpair : la donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises\",\"datePublished\":\"2024-08-02T14:15:49+00:00\",\"dateModified\":\"2024-08-26T13:08:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/\"},\"wordCount\":1021,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png\",\"articleSection\":[\"Actualit\u00e9s finance\",\"Actualit\u00e9s Trustpair\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/\",\"url\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/\",\"name\":\"La donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises - Trustpair\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png\",\"datePublished\":\"2024-08-02T14:15:49+00:00\",\"dateModified\":\"2024-08-26T13:08:07+00:00\",\"description\":\"D\u00e9couvrez comment Trustpair, en partenariat avec SwiftRef, collecte de la donn\u00e9e bancaire de r\u00e9f\u00e9rence pour \u00e9valuer les tiers. Lire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png\",\"contentUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png\",\"width\":1000,\"height\":524},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/blog\\\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Swiftref x Trustpair : la donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/\",\"name\":\"Trustpair\",\"description\":\"Solution leader de pr\u00e9vention de la fraude au virement et de contr\u00f4le RIB fournisseurs\",\"publisher\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#organization\",\"name\":\"Trustpair\",\"url\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-trustpair.svg\",\"contentUrl\":\"https:\\\/\\\/trustpair.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Logo-trustpair.svg\",\"width\":304,\"height\":73,\"caption\":\"Trustpair\"},\"image\":{\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/trustpair.com\\\/fr\\\/#\\\/schema\\\/person\\\/84e7e0fdbda12c03dbbe6629de190034\",\"name\":\"trustpair_2438\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g\",\"caption\":\"trustpair_2438\"},\"sameAs\":[\"http:\\\/\\\/trustpair.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises - Trustpair","description":"D\u00e9couvrez comment Trustpair, en partenariat avec SwiftRef, collecte de la donn\u00e9e bancaire de r\u00e9f\u00e9rence pour \u00e9valuer les tiers. Lire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/","og_locale":"fr_FR","og_type":"article","og_title":"La donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises - Trustpair","og_description":"D\u00e9couvrez comment Trustpair, en partenariat avec SwiftRef, collecte de la donn\u00e9e bancaire de r\u00e9f\u00e9rence pour \u00e9valuer les tiers. Lire.","og_url":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/","og_site_name":"Trustpair","article_published_time":"2024-08-02T14:15:49+00:00","article_modified_time":"2024-08-26T13:08:07+00:00","og_image":[{"width":1000,"height":524,"url":"https:\/\/trustpair.com\/wp-content\/uploads\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png","type":"image\/png"}],"author":"trustpair_2438","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"trustpair_2438","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/#article","isPartOf":{"@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/"},"author":{"name":"trustpair_2438","@id":"https:\/\/trustpair.com\/fr\/#\/schema\/person\/84e7e0fdbda12c03dbbe6629de190034"},"headline":"Swiftref x Trustpair : la donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises","datePublished":"2024-08-02T14:15:49+00:00","dateModified":"2024-08-26T13:08:07+00:00","mainEntityOfPage":{"@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/"},"wordCount":1021,"commentCount":0,"publisher":{"@id":"https:\/\/trustpair.com\/fr\/#organization"},"image":{"@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/#primaryimage"},"thumbnailUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png","articleSection":["Actualit\u00e9s finance","Actualit\u00e9s Trustpair"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/","url":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/","name":"La donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises - Trustpair","isPartOf":{"@id":"https:\/\/trustpair.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/#primaryimage"},"image":{"@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/#primaryimage"},"thumbnailUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png","datePublished":"2024-08-02T14:15:49+00:00","dateModified":"2024-08-26T13:08:07+00:00","description":"D\u00e9couvrez comment Trustpair, en partenariat avec SwiftRef, collecte de la donn\u00e9e bancaire de r\u00e9f\u00e9rence pour \u00e9valuer les tiers. Lire.","breadcrumb":{"@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/#primaryimage","url":"https:\/\/trustpair.com\/wp-content\/uploads\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png","contentUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/Trustpair-et-Swiftref-la-donnee-de-reference-1.png","width":1000,"height":524},{"@type":"BreadcrumbList","@id":"https:\/\/trustpair.com\/fr\/blog\/swiftref-x-trustpair-la-donnee-de-reference-est-cruciale-pour-les-entreprises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trustpair.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Swiftref x Trustpair : la donn\u00e9e de r\u00e9f\u00e9rence est cruciale pour les entreprises"}]},{"@type":"WebSite","@id":"https:\/\/trustpair.com\/fr\/#website","url":"https:\/\/trustpair.com\/fr\/","name":"Trustpair","description":"Solution leader de pr\u00e9vention de la fraude au virement et de contr\u00f4le RIB fournisseurs","publisher":{"@id":"https:\/\/trustpair.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trustpair.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trustpair.com\/fr\/#organization","name":"Trustpair","url":"https:\/\/trustpair.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trustpair.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/trustpair.com\/wp-content\/uploads\/2024\/07\/Logo-trustpair.svg","contentUrl":"https:\/\/trustpair.com\/wp-content\/uploads\/2024\/07\/Logo-trustpair.svg","width":304,"height":73,"caption":"Trustpair"},"image":{"@id":"https:\/\/trustpair.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/trustpair.com\/fr\/#\/schema\/person\/84e7e0fdbda12c03dbbe6629de190034","name":"trustpair_2438","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d12c0ac7da84e4d35dc796d48c46b8b4220ca5f66a673f8913d561eaf8371db?s=96&d=mm&r=g","caption":"trustpair_2438"},"sameAs":["http:\/\/trustpair.com"]}]}},"_links":{"self":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/posts\/7325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/comments?post=7325"}],"version-history":[{"count":0,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/posts\/7325\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/media\/7326"}],"wp:attachment":[{"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/media?parent=7325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/categories?post=7325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trustpair.com\/fr\/wp-json\/wp\/v2\/tags?post=7325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}